{"id":1648,"date":"2026-07-30T19:40:02","date_gmt":"2026-07-30T17:40:02","guid":{"rendered":"https:\/\/papersalfarb.com\/?post_type=product&#038;p=1648"},"modified":"2026-08-02T06:44:13","modified_gmt":"2026-08-02T04:44:13","slug":"de-la-bolcada-a-la-mortalla","status":"publish","type":"product","link":"https:\/\/papersalfarb.com\/cas\/producte\/de-la-bolcada-a-la-mortalla\/","title":{"rendered":"DE LA BOLCADA A LA MORTALLA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1038,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[23,36,34],"product_tag":[],"class_list":["post-1648","product","type-product","status-publish","has-post-thumbnail","product_cat-llibreria","product_cat-novetat","product_cat-valencia","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DE LA BOLCADA A LA MORTALLA - Papereria Papers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/papersalfarb.com\/cas\/producto-2\/de-la-bolcada-a-la-mortalla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DE LA BOLCADA A LA MORTALLA - Papereria Papers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/papersalfarb.com\/cas\/producto-2\/de-la-bolcada-a-la-mortalla\/\" \/>\n<meta property=\"og:site_name\" content=\"Papereria Papers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-02T04:44:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/producte\\\/de-la-bolcada-a-la-mortalla\\\/\",\"url\":\"https:\\\/\\\/papersalfarb.com\\\/producte\\\/de-la-bolcada-a-la-mortalla\\\/\",\"name\":\"DE LA BOLCADA A LA MORTALLA - Papereria Papers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/producte\\\/de-la-bolcada-a-la-mortalla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/producte\\\/de-la-bolcada-a-la-mortalla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/papersalfarb.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/bolcada-mortalla.jpg\",\"datePublished\":\"2026-07-30T17:40:02+00:00\",\"dateModified\":\"2026-08-02T04:44:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/producte\\\/de-la-bolcada-a-la-mortalla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/papersalfarb.com\\\/producte\\\/de-la-bolcada-a-la-mortalla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/producte\\\/de-la-bolcada-a-la-mortalla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/papersalfarb.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/bolcada-mortalla.jpg\",\"contentUrl\":\"https:\\\/\\\/papersalfarb.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/bolcada-mortalla.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/producte\\\/de-la-bolcada-a-la-mortalla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/papersalfarb.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\\\/\\\/papersalfarb.com\\\/botiga\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DE LA BOLCADA A LA MORTALLA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/#website\",\"url\":\"https:\\\/\\\/papersalfarb.com\\\/\",\"name\":\"Papereria Papers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/papersalfarb.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/#organization\",\"name\":\"Papereria Papers\",\"url\":\"https:\\\/\\\/papersalfarb.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/papersalfarb.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-pape-2019-1.png\",\"contentUrl\":\"https:\\\/\\\/papersalfarb.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-pape-2019-1.png\",\"width\":1369,\"height\":208,\"caption\":\"Papereria Papers\"},\"image\":{\"@id\":\"https:\\\/\\\/papersalfarb.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DE LA BOLCADA A LA MORTALLA - Papereria Papers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/papersalfarb.com\/cas\/producto-2\/de-la-bolcada-a-la-mortalla\/","og_locale":"es_ES","og_type":"article","og_title":"DE LA BOLCADA A LA MORTALLA - Papereria Papers","og_url":"https:\/\/papersalfarb.com\/cas\/producto-2\/de-la-bolcada-a-la-mortalla\/","og_site_name":"Papereria Papers","article_modified_time":"2026-08-02T04:44:13+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/papersalfarb.com\/producte\/de-la-bolcada-a-la-mortalla\/","url":"https:\/\/papersalfarb.com\/producte\/de-la-bolcada-a-la-mortalla\/","name":"DE LA BOLCADA A LA MORTALLA - Papereria Papers","isPartOf":{"@id":"https:\/\/papersalfarb.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/papersalfarb.com\/producte\/de-la-bolcada-a-la-mortalla\/#primaryimage"},"image":{"@id":"https:\/\/papersalfarb.com\/producte\/de-la-bolcada-a-la-mortalla\/#primaryimage"},"thumbnailUrl":"https:\/\/papersalfarb.com\/wp-content\/uploads\/2026\/06\/bolcada-mortalla.jpg","datePublished":"2026-07-30T17:40:02+00:00","dateModified":"2026-08-02T04:44:13+00:00","breadcrumb":{"@id":"https:\/\/papersalfarb.com\/producte\/de-la-bolcada-a-la-mortalla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/papersalfarb.com\/producte\/de-la-bolcada-a-la-mortalla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/papersalfarb.com\/producte\/de-la-bolcada-a-la-mortalla\/#primaryimage","url":"https:\/\/papersalfarb.com\/wp-content\/uploads\/2026\/06\/bolcada-mortalla.jpg","contentUrl":"https:\/\/papersalfarb.com\/wp-content\/uploads\/2026\/06\/bolcada-mortalla.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/papersalfarb.com\/producte\/de-la-bolcada-a-la-mortalla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/papersalfarb.com\/"},{"@type":"ListItem","position":2,"name":"Botiga","item":"https:\/\/papersalfarb.com\/botiga\/"},{"@type":"ListItem","position":3,"name":"DE LA BOLCADA A LA MORTALLA"}]},{"@type":"WebSite","@id":"https:\/\/papersalfarb.com\/#website","url":"https:\/\/papersalfarb.com\/","name":"Papereria Papers","description":"","publisher":{"@id":"https:\/\/papersalfarb.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/papersalfarb.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/papersalfarb.com\/#organization","name":"Papereria Papers","url":"https:\/\/papersalfarb.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/papersalfarb.com\/#\/schema\/logo\/image\/","url":"https:\/\/papersalfarb.com\/wp-content\/uploads\/2025\/09\/logo-pape-2019-1.png","contentUrl":"https:\/\/papersalfarb.com\/wp-content\/uploads\/2025\/09\/logo-pape-2019-1.png","width":1369,"height":208,"caption":"Papereria Papers"},"image":{"@id":"https:\/\/papersalfarb.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/papersalfarb.com\/cas\/wp-json\/wp\/v2\/product\/1648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/papersalfarb.com\/cas\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/papersalfarb.com\/cas\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/papersalfarb.com\/cas\/wp-json\/wp\/v2\/comments?post=1648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/papersalfarb.com\/cas\/wp-json\/wp\/v2\/media\/1038"}],"wp:attachment":[{"href":"https:\/\/papersalfarb.com\/cas\/wp-json\/wp\/v2\/media?parent=1648"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/papersalfarb.com\/cas\/wp-json\/wp\/v2\/product_brand?post=1648"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/papersalfarb.com\/cas\/wp-json\/wp\/v2\/product_cat?post=1648"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/papersalfarb.com\/cas\/wp-json\/wp\/v2\/product_tag?post=1648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}